{"id":6419,"date":"2024-05-08T13:58:56","date_gmt":"2024-05-08T13:58:56","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/?p=6419"},"modified":"2024-05-08T13:58:57","modified_gmt":"2024-05-08T13:58:57","slug":"biblio-in-presentato-il-nuovo-progetto-di-rete-della-pro-loco-curtomartino","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2024\/05\/08\/biblio-in-presentato-il-nuovo-progetto-di-rete-della-pro-loco-curtomartino\/","title":{"rendered":"Biblio In &#8211; presentato il nuovo progetto di rete della Pro Loco &#8220;Curtomartino&#8221;"},"content":{"rendered":"\n<p>Marted\u00ec 30 aprile, nella Biblioteca Comunale di Acquaviva delle Fonti, si \u00e8 tenuta la presentazione del progetto <strong><em>Biblio In,<\/em><\/strong> che coinvolge anche Casamassima, e con il quale si vuole incrementare la proposta culturale e sociale attorno alle Biblioteche Comunali dei due comuni interessati. Biblioteche che non saranno pi\u00f9 intese come un mero luogo di studio e ricerca, ma come entit\u00e0 libere, senza vincoli. Una nuova concezione di servizio che va incontro ai tempi moderni e si avvicina ai suoi fruitori, ovunque essi siano.<\/p>\n\n\n\n<p>Biblio In \u00e8 risultato vincitore del bando \u201c<strong>Biblioteche e Comunit\u00e0<\/strong>\u201d, alla seconda edizione, promosso da <strong>Fondazione CON IL SUD<\/strong> e <strong>Centro per il Libro e la lettura<\/strong>, in collaborazione con l\u2019Associazione Nazionale del Comuni Italiani (<strong>ANCI<\/strong>).<\/p>\n\n\n\n<p>La sfida che si vuol mettere in atto attraverso il progetto Biblio In \u00e8 quella di <strong>migliorare la fruizione delle biblioteche e consolidarne la funzione socio-culturale<\/strong>, attraverso il <strong>miglioramento dei servizi di accesso<\/strong>, l\u2019<strong>incremento del patrimonio bibliotecario<\/strong>, i <strong>servizi di supporto alla lettura e allo studio<\/strong>, l\u2019<strong>attivazione di presidi culturali periferici<\/strong> (ospedale, scuole, parrocchie) quali primo miglio di attrazione verso la lettura.<\/p>\n\n\n\n<p>Il complesso dei servizi offerti generer\u00e0 un cambiamento di rotta teso a <strong>comprimere le diseguaglianze<\/strong>, <strong>creare pari opportunit\u00e0<\/strong>, <strong>riconoscere la centralit\u00e0 dell\u2019individuo<\/strong>, soprattutto a rafforzare gli aspetti educativi e formativi, di orientamento allo studio o al lavoro, di educazione e\/o rieducazione alla lettura anche attraverso l\u2019utilizzo dei dispositivi tecnologici.<\/p>\n\n\n\n<p>Sul progetto <strong>Azzurra Acciani<\/strong>, Assessora alla Cultura di Casamassima, si \u00e8 cos\u00ec espressa: \u201cLa bellezza del progetto Biblio In sta nel fatto che, grazie ad esso, \u00e8 l&#8217;istituzione Biblioteca che va incontro ai cittadini. Soprattutto di quei cittadini che per disparate condizioni vivono pi\u00f9 ai margini della comunit\u00e0, come stranieri, diversamente abili, infermi, ma anche giovanissimi che spesso associano alle biblioteche l&#8217;idea di luoghi distanti o austeri. Per questo ringrazio la Pro Loco Curtomartino che ha pensato a questo meraviglioso progetto e tutti i partner e le scuole che hanno deciso di aderirvi fornendo il proprio originale e indispensabile contributo\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-4.jpg\" alt=\"\" class=\"wp-image-6420\" srcset=\"https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-4.jpg 800w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-4-300x300.jpg 300w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-4-150x150.jpg 150w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-4-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Ha aperto i lavori il neo <strong>Presidente della Pro Loco \u201cCurtomartino\u201d<\/strong> di Acquaviva, <strong>Alessandro Macchia<\/strong>, che ha ricordato come le attivit\u00e0 della Pro Loco, capofila del progetto, trovino molto spazio all\u2019interno della Biblioteca Comunale: prestito interbibliotecario, ampliamento orari di apertura al pubblico, supporto didattico allo studio, tandem linguistico e preparazione ai test di accesso per le facolt\u00e0 a numero chiuso. &#8220;Con \u201cBiblio In\u201d si vuole ulteriormente puntare sulla cultura e sull\u2019accessibilit\u00e0, attraverso \u201cun progetto che si va ad intersecare all\u2019interno della proposta attuale che riguarda la biblioteca comunale e che sar\u00e0 una grande opportunit\u00e0 per il territorio, perch\u00e9 vedr\u00e0 la gente di Acquaviva e Casamassima essere la vera protagonista di questo nuovo modo di diffondere la cultura&#8221;.<\/p>\n\n\n\n<p><strong>Stefania Carella<\/strong>, <strong>Vice Presidente della Pro Loco e Responsabile del progetto Biblio In<\/strong>, ha voluto in primis elogiare il lavoro di tutti i soci e i partner coinvolti in Biblio In. \u201cAver raggiunto questo traguardo, creando rete tra la biblioteca di Acquaviva e quella di Casamassima, \u00e8 stato davvero molto bello e molto gradito\u201d. Menzione speciale anche per \u201ci ragazzi della Pro Loco\u201d, chiamati cos\u00ec nel 2014. Un gruppo di studenti universitari che necessitava di una biblioteca maggiormente aperta, pi\u00f9 funzionale per le loro esigenze di studio e di formazione. Cosa fecero per farsi sentire e cercare di cambiare qualcosa? Manifestarono, in maniera pacifica ovviamente, cercando di sfruttare i canali social per arrivare ad avere pi\u00f9 risonanza e pi\u00f9 supporto e ottenere cos\u00ec una biblioteca dove sentirsi al sicuro. \u201cRitrovarsi oggi, dopo 10 anni &#8211; continua Carella &#8211; a vivere un progetto dove doniamo alle comunit\u00e0 tante altre attivit\u00e0 e servizi, pi\u00f9 completi e strutturati,\u00a0 lo reputo un completamento di questo percorso, ma anche un nuovo punto di partenza\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-7.jpg\" alt=\"\" class=\"wp-image-6422\" srcset=\"https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-7.jpg 800w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-7-300x300.jpg 300w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-7-150x150.jpg 150w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-7-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>La sfida che la Pro Loco di Acquaviva vuol mettere in atto attraverso il progetto Biblio In \u00e8 quella di <strong>migliorare la fruizione delle biblioteche e consolidarne la funzione socio-culturale<\/strong>, attraverso il <strong>miglioramento dei servizi di accesso<\/strong>, l\u2019<strong>incremento del patrimonio bibliotecario<\/strong>, i <strong>servizi di supporto alla lettura e allo studio<\/strong>, l\u2019<strong>attivazione di presidi culturali periferici<\/strong> (ospedale, scuole, parrocchie) quali primo miglio di attrazione verso la lettura.<\/p>\n\n\n\n<p>Il complesso dei servizi offerti generer\u00e0 un cambiamento di rotta teso a <strong>comprimere le diseguaglianze<\/strong>, <strong>creare pari opportunit\u00e0<\/strong>, <strong>riconoscere la centralit\u00e0 dell\u2019individuo<\/strong>, soprattutto a rafforzare gli aspetti educativi e formativi, di orientamento allo studio o al lavoro, di educazione e\/o rieducazione alla lettura anche attraverso l\u2019utilizzo dei dispositivi tecnologici.<\/p>\n\n\n\n<p>Per la Citt\u00e0 Metropolitana di Bari, <strong>Francesca Pietroforte<\/strong>, <strong>Consigliera con delega alla Cultura<\/strong>. \u201cL\u2019importanza della programmazione in cultura \u00e8 fondamentale per riuscire ad ottenere fondi e finanziamenti, senza i quali sarebbe impossibile sviluppare progetti e creare opportunit\u00e0\u201d. Un elogio anche alle capacit\u00e0 che hanno avuto i professionisti della Pro Loco nel realizzare un progetto altamente competitivo a livello nazionale, riuscendo a raccogliere i fondi necessari per promuovere la lettura, la cultura e l\u2019inclusione. La Consigliera Pietroforte ha evidenziato, in ultimo, come il progetto Biblio In stia raccogliendo molto interesse e consensi nei due Comuni, tanto da ricordarle un altro progetto tanto amato dagli studenti soprattutto di Acquaviva: <strong>Biblio In Rete<\/strong>. Un\u2019iniziativa portata avanti da due persone in particolare, artefici dello sviluppo di questo progetto: <strong>Zenia Benemerito<\/strong> e il tanto amato <strong>Felice Bruno<\/strong>.<\/p>\n\n\n\n<p>Per il Comune di Acquaviva, l\u2019<strong>Assessora alla Cultura, Mariagrazia Barbieri<\/strong>, che ha elogiato \u201cil progetto di rete ideato dalla Pro Loco. Un progetto realizzato sulla base di collaborazioni tra istituzioni, associazioni del territorio, scuole e figure professionali. Questo gruppo di partner \u00e8 molto importante perch\u00e9 se da un lato ci sono le istituzioni che devono spingere affinch\u00e8 il progetto possa realizzarsi, dall\u2019altro il ruolo di tutti gli altri partner \u00e8 strategico sia nello sviluppo, sia nel coordinamento. Ancora un ringraziamento alla Pro Loco Curtomartino, perch\u00e8 \u00e8 una realt\u00e0 del territorio molto preziosa, professionale e che si spende nella cura e nella realizzazione di questi progetti con grande tenacia ed entusiasmo\u201d.<\/p>\n\n\n\n<p>Il <strong>Sindaco Lenoci<\/strong> ha confermato che \u201cin continuit\u00e0 con il lavoro iniziato dalla passata amministrazione, la biblioteca di Acquaviva trover\u00e0 una nuova sede nell\u2019ex Macello Comunale. Un luogo che potr\u00e0 accogliere molti pi\u00f9 studenti, un luogo che offrir\u00e0 anche spazi di condivisione e di relazione, che verr\u00e0 consegnato alla comunit\u00e0 il prima possibile. Valorizzare la biblioteca comunale e tutti i servizi annessi sar\u00e0 di fondamentale importanza per lo sviluppo culturale di tutto il paese\u201d.<\/p>\n\n\n\n<p><strong>Perch\u00e9 \u201cBiblio In\u201d?<\/strong><\/p>\n\n\n\n<p>&nbsp;Il titolo evoca la filosofia del progetto: essere inclusivi, andare incontro, coinvolgere. Le diverse declinazioni del titolo in tre tipologie di azione, ne indicano invece le modalit\u00e0. Le attivit\u00e0 previste rappresentano le azioni che saranno attivate, nell\u2019intero ambito territoriale, in base ai diversi obiettivi e risultati progettuali, secondo le seguenti linee di intervento.<\/p>\n\n\n\n<p>&#8220;<strong>Biblio In Movimento<\/strong>&#8221; &#8211; la lettura come fattore di inclusione, vicinanza, aggregazione e crescita. Una biblioteca itinerante in sella ad una bici animer\u00e0 i \u201cpresidi\u201d periferici e coinvolger\u00e0 fasce a rischio di marginalit\u00e0.<\/p>\n\n\n\n<p>&#8220;<strong>Biblio In ascolto\/ informa<\/strong>&#8221; &#8211; la biblioteca come agente e mediatore sociale delle fasce pi\u00f9 deboli, anche straniere. Servizi di sostegno didattico, informazione e formazione, anche ai docenti, sulle problematiche infantili e adolescenziali.<\/p>\n\n\n\n<p>&#8220;<strong>Biblio In relazione<\/strong>&#8221; &#8211; accessibilit\u00e0 e tecnologia, fattori di attrazione per la fruizione e la produzione culturale: incremento del patrimonio librario, estensione degli orari\/giorni di accesso, messa in rete delle biblioteche comunali. I dispositivi tecnologici saranno strumenti abilitanti per l\u2019interazione socio culturale con i pi\u00f9 giovani.<\/p>\n\n\n\n<p><strong>Seguendo Biblio In su Facebook e Instagram, sar\u00e0 possibile conoscere tutte le sfaccettature del progetto e tutte le attivit\u00e0 e gli eventi dei partner coinvolti.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-10.jpg\" alt=\"\" class=\"wp-image-6421\" srcset=\"https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-10.jpg 800w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-10-300x300.jpg 300w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-10-150x150.jpg 150w, https:\/\/casamassima.lavocedelpaese.info\/wp-content\/uploads\/2024\/05\/Evento-10-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec 30 aprile, nella Biblioteca Comunale di Acquaviva delle Fonti, si \u00e8 tenuta la presentazione del progetto Biblio In, che<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6419","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/6419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=6419"}],"version-history":[{"count":1,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/6419\/revisions"}],"predecessor-version":[{"id":6423,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/6419\/revisions\/6423"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=6419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=6419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=6419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}