{"id":4833,"date":"2023-07-29T05:31:43","date_gmt":"2023-07-29T05:31:43","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/07\/29\/proteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile\/"},"modified":"2023-07-29T05:31:43","modified_gmt":"2023-07-29T05:31:43","slug":"proteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/07\/29\/proteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile\/","title":{"rendered":"\u201cProteggiamoci dal Caldo\u201d, la campagna di sensibilizzazione di Polizia Locale e Protezione Civile"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bTuri \u2013 La Voce del Paese\u00a0<\/p>\n<p>Dieci regole semplici indicate dal Ministero della Salute per fronteggiare questa emergenza di caldo. \u00c8 stata questa l\u2019attivit\u00e0 svolta ieri mattina dalla Polizia Locale, diretta dal Comandante dott. Nicola Leone, unitamente al Gruppo comunale di Protezione Civile nel corso dello svolgimento del mercato settimanale del venerd\u00ec.<\/p>\n<p>\u00abUn\u2019azione di sensibilizzazione e di informazione rivolta all\u2019intera cittadinanza, specie alle fasce deboli, tra cui gli anziani, al fine di dare consigli utili su come fronteggiare questa eccezionale, oltrech\u00e9 anomala, ondata di caldo\u00bb \u2013 dichiara il Comandante Leone, ringraziando \u00abi volontari del Gruppo comunale di Protezione Civile per il prezioso contributo che apportano all\u2019intera comunit\u00e0 turese\u00bb.<\/p>\n<p> [<a href=\"https:\/\/turi.lavocedelpaese.info\/proteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile\/?utm_source=rss&amp;utm_medium=rss&amp;utm_campaign=proteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile\">See image gallery at turi.lavocedelpaese.info<\/a>] <\/p>\n<p> [<a href=\"https:\/\/turi.lavocedelpaese.info\/proteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile\/?utm_source=rss&amp;utm_medium=rss&amp;utm_campaign=proteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile\">See image gallery at turi.lavocedelpaese.info<\/a>] <\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F29%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F29%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F29%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F29%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F29%2Fproteggiamoci-dal-caldo-la-campagna-di-sensibilizzazione-di-polizia-locale-e-protezione-civile%2F&amp;linkname=%E2%80%9CProteggiamoci%20dal%20Caldo%E2%80%9D%2C%20la%20campagna%20di%20sensibilizzazione%20di%20Polizia%20Locale%20e%20Protezione%20Civile\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bTuri \u2013 La Voce del Paese\u00a0 Dieci regole semplici indicate dal Ministero della Salute per fronteggiare questa emergenza<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-4833","post","type-post","status-publish","format-standard","hentry","category-regione"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=4833"}],"version-history":[{"count":0,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4833\/revisions"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=4833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=4833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=4833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}