{"id":4360,"date":"2023-07-09T12:35:45","date_gmt":"2023-07-09T12:35:45","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/07\/09\/la-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova-13\/"},"modified":"2023-07-09T12:35:45","modified_gmt":"2023-07-09T12:35:45","slug":"la-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova-13","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/07\/09\/la-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova-13\/","title":{"rendered":"La pazienza, protagonista al prossimo congresso dei Testimoni di Geova"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bAcquaviva \u2013 La Voce del Paese\u00a0<\/p>\n<p><strong>Giuseppe Carbonara<\/strong>, Portavoce dei Testimoni di Geova per Puglia e Basilicata\u00a0<\/p>\n<p><em>A Bari dal 14 al 16 luglio tre giorni per imparare a essere pazienti<\/em><\/p>\n<p>In un\u2019epoca come la nostra, caratterizzata dal \u201ctutto e subito\u201d, stress e scarso autocontrollo, la pazienza non \u00e8 pi\u00f9 considerata una virt\u00f9. Per molti essere pazienti significa rassegnarsi agli eventi della vita. Ma cos\u2019\u00e8 la pazienza? Essere pazienti pu\u00f2 migliorare la nostra vita e i rapporti con gli altri? A queste e ad altre domande risponder\u00e0 il congresso dei Testimoni di Geova del 2023 dal tema \u201cSiate Pazienti\u201d in programma dal 14 al 16 Luglio, a Bari presso il Nuovo Padiglione della Fiera del Levante.<\/p>\n<p>\u201cLa pazienza \u00e8 una qualit\u00e0 importante che pu\u00f2 essere utile a tutti nella vita quotidiana\u201d, dice Giuseppe Carbonara portavoce dei Testimoni di Geova per Puglia e Basilicata. \u201cNonostante le buone intenzioni, per\u00f2, mantenere la pazienza di fronte ai tanti problemi che la vita ci riserva pu\u00f2 essere una sfida. Trascorrere tre giorni approfondendo gli aspetti di questa qualit\u00e0 sar\u00e0 molto istruttivo\u201d.<\/p>\n<p>Da venerd\u00ec a domenica si parler\u00e0 della pazienza, evidenziandone il valore pratico attraverso esempi tratti dalla Bibbia. I momenti pi\u00f9 attesi saranno il battesimo dei nuovi fedeli, che sar\u00e0 celebrato sabato mattina, e un video racconto in due parti, che sar\u00e0 presentato durante le sessioni del sabato e della domenica pomeriggio. Quest\u2019anno sono in programma in tutto il mondo circa 6.000 congressi dal tema \u201cSiate Pazienti\u201d. Solo in Italia, pi\u00f9 di 75 congressi si terranno in 14 citt\u00e0.<\/p>\n<p>A causa della pandemia, nel 2020 i Testimoni di Geova avevano cancellato i loro eventi in presenza in tutto il mondo e per tre anni li hanno tenuti online in pi\u00f9 di 500 lingue. \u201cGrazie ai nostri congressi online sono stati raggiunti milioni di persone in tutto il mondo e si \u00e8 riusciti a proteggere la salute dei tanti partecipanti. Quest\u2019anno per\u00f2 non vediamo l\u2019ora di ritrovarci finalmente in presenza\u201d conclude Giuseppe Carbonara.<\/p>\n<p>Da oltre 100 anni i Testimoni di Geova tengono grandi eventi in stadi, arene, centri congressi e teatri in tutto il mondo. Come sempre, l\u2019appuntamento \u00e8 aperto al pubblico. Per ulteriori informazioni sul programma o per trovare le altre sedi e date dei congressi, visitate il sito <a href=\"https:\/\/www.jw.org\/it\/\">jw.org<\/a> e navigate nella scheda \u201cChi siamo\u201d.<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F08%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F08%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F08%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F08%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F08%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F09%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova-3%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F09%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova-3%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F09%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova-3%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F09%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova-3%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F07%2F09%2Fla-pazienza-protagonista-al-prossimo-congresso-dei-testimoni-di-geova-3%2F&amp;linkname=La%20pazienza%2C%20protagonista%20al%20prossimo%20congresso%20dei%20Testimoni%20di%20Geova\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bAcquaviva \u2013 La Voce del Paese\u00a0 Giuseppe Carbonara, Portavoce dei Testimoni di Geova per Puglia e Basilicata\u00a0 A<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-4360","post","type-post","status-publish","format-standard","hentry","category-regione"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=4360"}],"version-history":[{"count":0,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4360\/revisions"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=4360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=4360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=4360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}