{"id":3151,"date":"2023-05-20T15:28:46","date_gmt":"2023-05-20T15:28:46","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/05\/20\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-85\/"},"modified":"2023-05-20T15:28:46","modified_gmt":"2023-05-20T15:28:46","slug":"e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-85","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/05\/20\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-85\/","title":{"rendered":"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bGioia \u2013 La Voce del Paese\u00a0<\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p><strong>Qui sotto tutte le novit\u00e0 presenti in questo numero. Buona lettura a tutti.<\/strong><\/p>\n<p>L\u2019Editoriale. Raid notturni tra le pattumelle dei rifiuti \u201cscorrettamente\u201d conferiti di Donato Stoppini<\/p>\n<p>L\u2019angolo dell\u2019Ambiente\u201d. Bandiere Blu. La Puglia, con 22 bollini di qualit\u00e0, al secondo posto in Italia<\/p>\n<p>Il gusto amaro del pregiudizio di Iole Pitarra<\/p>\n<p>Luci ed ombre sulla valorizzazione delle sette arti di Ricciotto Canudo di Donato Stoppini<\/p>\n<p>Mafia\u2026 Per\u00f2 parlatene!<\/p>\n<p>\u201cGiallo\u2026 Irrisolto! Sindaco, ma \u00e8 agghiacciante!\u201d<\/p>\n<p>Pensieri e parole. Ogni Donna \u00e8 Mamma di Enzo Cuscito<\/p>\n<p>Invasione di suolo pubblico. Prevista doppia sanzione per i fruttivendoli<\/p>\n<p>Grave incidente stradale sulla Gioia-Noci. Ferita infermiera 51enne<\/p>\n<p>Bonus occhiali 2023, come avere i 50 euro: a chi spetta e cosa bisogna sapere<\/p>\n<p>Fidas\u2026 Si dona anche il giorno della festa della mamma<\/p>\n<p>\u201cOtt\u00e0\u201d, la cantina gastronomica di Ottavio Surico<\/p>\n<p>La Croce Rossa e la Granarolo su Rai News<\/p>\n<p>Il Gruppo Vincenziano in piazza e in gita a Otranto<\/p>\n<p>Gli auguri alle mamme del Quartiere Rinascita<\/p>\n<p>\u201cCanudo e la valorizzazione delle sette arti\u201d<\/p>\n<p>Tre scrittrici gioiesi al Salone del Libro di Torino<\/p>\n<p>La \u201cCultura dell\u2019Intelligence\u201d \u2013 dalle origini ai giorni nostri<\/p>\n<p>\u201cLa 36\u00aa Aerobrigata Interdizione Strategica\u201d<\/p>\n<p>Il 36\u00b0 Stormo Caccia apre i cancelli e si mette in \u201cmostra\u201d<\/p>\n<p>I festeggiamenti in onore di Santa Rita<\/p>\n<p>\u201cE sia\u201d di Grazia Procino \u2013 Medaglia d\u2019Onore e finalista in contesti internazionali<\/p>\n<p>\u201cMuri Animati\u201d animati alla Carano<\/p>\n<p>Patologie del fegato: sabato 27 maggio screening gratuito<\/p>\n<p>Mirea Milano \u2013 Quando una passione stravolge la vita<\/p>\n<p>La strada non \u00e8 una giungla\u2026 a scuola!<\/p>\n<p>La Notte del Liceo Classico<\/p>\n<p>Giornata FAI: alla scoperta di Masseria Losciale e Castello Marchione\u201d<\/p>\n<p>Losapio \u2013 Donna, vita, libert\u00e0: le strade dell\u2019Iran<\/p>\n<p>Progetto \u201cPetali Viola\u201d: ogni Petalo\u2026una storia legata al genere<\/p>\n<p>Laboratorio di Architettura letteraria al Canudo<\/p>\n<p>Mattia Zenzola \u2013 vincitore di \u201cAmici\u201d \u2013 ha origini gioiesi<\/p>\n<p>Multiculturalit\u00e0 \u2013 Tutti interconnessi con altri mondi<\/p>\n<p>Luana Montone \u2013 I Lumied a Ginevra con i Boomdabash<\/p>\n<p>A lezione di \u201cPlastic free\u201d alla San Filippo Neri<\/p>\n<p>\u201cInnamor\u2019Arti\u201d tra poesia, pittura e danza di Dalila Bellacicco<\/p>\n<p>Aperitivo per la salute: storie di successo, prevenzione e coraggio<\/p>\n<p>Admo \u2013 Il gioiese Filippo Antonicelli ha donato e salvato una vita<\/p>\n<p>Addio, Paoletta!<\/p>\n<p>Ciao, Filippo!<\/p>\n<p>La festa di San Filippo Neri di Marisa D\u2019Elia<\/p>\n<p>\u201cLa poesia della settimana\u201d a cura di Giacomo Leronni<\/p>\n<p>Raccontando in versi di Enzo Diana<\/p>\n<p>Alchimia delle emozioni di Gianna Evangelista<\/p>\n<p>Il professore (storie di vite e di magie) di Giovanni Vasco. Minguccio \u201cgiovane\u201d attivista politico<\/p>\n<p>Playoff promozione B2. Gioiella Volley Gioia passa alla fase 2<\/p>\n<p>Team Special Minozzi Gioia Campione d\u2019Italia!<\/p>\n<p>Nava Asd Pallavolo Gioia batte in casa il Prisma Massafra di Francesco Pavone<\/p>\n<p>Boxe. Esperienza soddisfacente per il Team Fico al 6\u00b0 Trofeo \u201cMasseria Ruina\u201d<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-17%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-17%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-17%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-17%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-17%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-16%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-16%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-16%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-16%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F20%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-16%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bGioia \u2013 La Voce del Paese\u00a0 Qui sotto tutte le novit\u00e0 presenti in questo numero. Buona lettura a<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-3151","post","type-post","status-publish","format-standard","hentry","category-regione"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/3151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":0,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/3151\/revisions"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=3151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=3151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}