{"id":2775,"date":"2023-05-05T00:32:33","date_gmt":"2023-05-05T00:32:33","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/05\/05\/entra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei-10\/"},"modified":"2023-05-05T00:32:33","modified_gmt":"2023-05-05T00:32:33","slug":"entra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei-10","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/05\/05\/entra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei-10\/","title":{"rendered":"Entra nel vivo in San Domenico la festa della Madonna di Pompei"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bGioia \u2013 La Voce del Paese\u00a0<\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p>\u201cLa preghiamo ogni giorno, sempre, la Madonna, ma abbiamo sentito il bisogno di farlo ancora con pi\u00f9 forza. Le abbiamo riservato e dedicato un mese intero: maggio, il mese delle rose, dei fiori, della primavera.<\/p>\n<p>Tante le feste a Lei dedicate.<\/p>\n<p>Questo trattamento, se ci pensiamo bene, lo riserviamo solo alla persona a noi pi\u00f9 cara, alle nostre mamme. Ci hanno amato, desiderato, atteso, fatti nascere, cresciuti, curati, in modo unico. Tutto dobbiamo a loro. Non cessiamo mai di sentirle a noi vicine, di chiamarle, di ricorrere a loro sempre: <em>mamma mia! Aiutami tu.<\/em><\/p>\n<p>Ancora pi\u00f9 forte \u00e8 il nostro ricorrere a Maria, la Madre di Dio e la Madre nostra.<\/p>\n<p>La preghiamo con il saluto dell\u2019Arcangelo Gabriele: <strong>Ave Maria! <\/strong>Senza stancarci mai. Lo ripetiamo all\u2019infinito come per essere tenuti nelle Sue braccia ed essere protetti, per dirLe tutta la nostra fiducia, il nostro bisogno, l\u2019aiuto che a Lei cerchiamo. Mai respinti, sempre accolti, protetti, aiutati. Il solo invocarLa, pregarLa, non ci fa sentire mai soli.<\/p>\n<p>Anche noi, piccola Confraternita a Lei dedicata, la\u00a0<strong>Confraternita di Maria S.S. del Rosario in San Domenico a Gioia del Colle<\/strong>, La veneriamo, La preghiamo tanto, La festeggiamo: \u00e8 la nostra Mamma Celeste.<strong> \u201cA te ricorriamo esuli figli di Eva, a Te sospiriamo, ors\u00f9 Avvocata nostra. Prega per noi peccatori, adesso e nell\u2019ora della nostra morte!\u201d<\/strong><\/p>\n<p>Infatti, venerd\u00ec 5 maggio, con l\u2019inizio del triduo solenne, la Festa dell\u20198 maggio, giorno della Supplica alla Madonna di Pompei, entra nel vivo.<\/p>\n<p>Unisciti a noi.\u00a0<\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p>Vieni, preghiamoLa insieme.<\/p>\n<p>Benediciamo insieme <strong>\u201cil Frutto del Tuo seno: Ges\u00f9\u201d.<\/strong><\/p>\n<p>Questa la missione di Maria: portarci a Ges\u00f9.<\/p>\n<p>Se stiamo con Lei, amiamo Ges\u00f9 che con la Sua morte e la Sua Resurrezione ci ha salvati.<\/p>\n<p><strong>PROGRAMMA DEL TRIDUO E DELLA FESTA<\/strong><\/p>\n<p><strong>Venerd\u00ec 5 maggio<\/strong> ore 17:15 Santo Rosario e preghiera della Novena, a seguire Celebrazione Eucaristica;<\/p>\n<p><strong>Sabato 6 maggio<\/strong>: ore 17:15 Santo Rosario e preghiera della Novena, a seguire Celebrazione Eucaristica;<\/p>\n<p><strong>Domenica 7 maggio<\/strong>: Ore 8:00 S. Messa\u00a0 della V Domenica di Pasqua;<\/p>\n<p>Ore 17:15 Santo Rosario e preghiera della Novena, a seguire Celebrazione Eucaristica. Le tre serate del triduo saranno presiedute da <strong>Don Andrea Wisniewski<\/strong><\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p><strong>Luned\u00ec 8 Maggio<\/strong>:<strong>\u00a0 <\/strong>Ore 10:30 S. Messa solenne presieduta dal nostro padre spirituale <strong>Don Tonino Posa<\/strong>.\u00a0 Nel Corso della Celebrazione Eucaristica vi sar\u00e0 l\u2019ingresso di una nuova consorella. A seguire sar\u00e0 recitato il Rosario Meditato, prima della Supplica Solenne alla B.V. del Santo Rosario di Pompei.<\/p>\n<p>Nel Pomeriggio alle 17:30 recita del S. Rosario e Celebrazione Eucaristica presieduta da <strong>Mons. Domenico Ciavarella<\/strong>, nel corso della quale saranno benedetti i Rosari da distribuire ai fedeli.<\/p>\n<p>Vieni, la Madonna preghiamoLa insieme!<\/p>\n<p>Saranno i fiori pi\u00f9 belli che gradir\u00e0\u201d.<\/p>\n<p class=\"has-text-align-right\"><strong>Confraternita SS. Rosario<\/strong><\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F05%2F04%2Fentra-nel-vivo-in-san-domenico-la-festa-della-madonna-di-pompei%2F&amp;linkname=Entra%20nel%20vivo%20in%20San%20Domenico%20la%20festa%20della%20Madonna%20di%20Pompei\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bGioia \u2013 La Voce del Paese\u00a0 \u201cLa preghiamo ogni giorno, sempre, la Madonna, ma abbiamo sentito il bisogno<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2775","post","type-post","status-publish","format-standard","hentry","category-regione"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/2775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=2775"}],"version-history":[{"count":0,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/2775\/revisions"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=2775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=2775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=2775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}