{"id":2481,"date":"2023-04-22T18:38:26","date_gmt":"2023-04-22T18:38:26","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/04\/22\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-48\/"},"modified":"2023-04-22T18:38:26","modified_gmt":"2023-04-22T18:38:26","slug":"e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-48","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/04\/22\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-48\/","title":{"rendered":"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bGioia \u2013 La Voce del Paese\u00a0<\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p><strong>Tutte le novit\u00e0 presenti in questo numero. Buona lettura a tutti.<\/strong><\/p>\n<p>Editoriale: \u201c75mila \u20ac per Percorsi di gusto e tradizione della terra murgiana\u201d di Donato Stoppini<\/p>\n<p>M5S. \u201cIl problema sicurezza a Gioia esiste. Sindaco, prenda spunto dal suo collega De Caro\u201d<\/p>\n<p>Bicibus e Pums<\/p>\n<p>Intervista a Franco Gisotti, presidente della Bottega<\/p>\n<p>Manila Gorio annuncia a Palazzo Romano la sua candidatura a sindaco di Bari<\/p>\n<p><strong>Refe<\/strong>rendum contro la guerra<\/p>\n<p>Intervista al \u201cdecano\u201d della sinistra gioiese. Il consigliere Paolo Covella<\/p>\n<p>Disagi Trenitalia, lettera aperta dell\u2019On. Lavarra ai parlamentari pugliesi<\/p>\n<p>25 aprile 2023<\/p>\n<p>\u201cL\u2019angolo dell\u2019Ambiente\u201d. Uomini e fauna selvatica. Convivenza possibile?<\/p>\n<p>\u201cL\u2019Autonomia differenziata, la grande bugia\u201d<\/p>\n<p>Valerio Pastore narra Toulouse Lautrec per Editions-eyrolles<\/p>\n<p>Ancora sangue sulle strade gioiesi. Nuovo agguato in pieno centro<\/p>\n<p>AVVISO AI CITTADINI: anticipato il mercato settimanale<\/p>\n<p>Fidas \u2013 Il dono della vita<\/p>\n<p>\u00abGiovani con Gioia\u00bb si presenta alla citt\u00e0 di Giovanni Capotorto<\/p>\n<p>Giovani con Gioia \u2013 Un iter entusiasmante<\/p>\n<p>Joha on the road \u2013 Gioia invasa dalle \u201cvespe\u201d<\/p>\n<p>1\u00b0 Maggio \u2013 Grande festa a Montursi<\/p>\n<p>Festival per l\u2019infanzia \u201cTeatri d\u2019acqua\u201d\u2026ma non a Gioia<\/p>\n<p>Clirim, la sua storia e noi ragazzi della II A<\/p>\n<p>In processione le reliquie romane di S. Filippo Neri<\/p>\n<p>Il futuro dei vaccini ad mRNA, fra l\u2019entusiasmo di alcuni e i dubbi di tanti di Gianvito Masi<\/p>\n<p>Consultorio \u2013 Manovre di disostruzione pediatrica<\/p>\n<p>Gli studenti della Carano incontrano Daniele Nicastro<\/p>\n<p>Al Rossini A.Ge.A. con \u201cNiente da dichiarare?\u201d<\/p>\n<p>L\u2019effimero come quintessenza dell\u2019umano di Grazia Procino<\/p>\n<p>Teatro per l\u2019infanzia \u2013 I semi del cambiamento di Iole Pitarra<\/p>\n<p>Approvato il Piano Sociale di Zona 2022-2024 con fondi per oltre 10 milioni di euro<\/p>\n<p>Fratres\u2026 si torna a donare!<\/p>\n<p>Cosa fare quando un animale selvatico uccide un umano?<\/p>\n<p>Salotto letterario \u2013 Le rose di Atacama di Vito Difino<\/p>\n<p>Volontariato. Insieme per aprire nuovi percorsi di solidariet\u00e0 di Dalila Bellacicco<\/p>\n<p>Il professore (storie di vite e di magie) di Giovanni Vasco. \u201cMinguccio, formaggi e liquori\u201d<\/p>\n<p>\u201cLa poesia della settimana\u201d a cura di Giacomo Leronni<\/p>\n<p>Raccontando in versi di Enzo Diana<\/p>\n<p>La parola nuda di Elisabetta Destasio Vettori<\/p>\n<p>Alchimia delle emozioni di Gianna Evangelista<\/p>\n<p>Le \u201ctappe\u201d di Gioia Running in attesa del 7 maggio<\/p>\n<p>Gioiella Academy Volley Gioia \u2013 Asem Bari<\/p>\n<p>Asd Academy Volley Gioia \u2013 La \u201cvoce\u201d del tecnico Leo Virelli<\/p>\n<p>Asd Pallavolo Gioia<\/p>\n<p>NVG Joy Volley, vittoria contro Volley Casoria per continuare a credere nei playoff<\/p>\n<p>NVG Joy Volley, Giuseppe Bitetti: \u00abI playoff? \u00c8 difficile, ma noi dobbiamo crederci\u00bb<\/p>\n<p>\u00a0\u201cScoiattoli Big\u201d della Junior basket Minozzi a Rutigliano<\/p>\n<p>Addio Nunzio!<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-13%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-13%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-13%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-13%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-13%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-12%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-12%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-12%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-12%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F22%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-12%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bGioia \u2013 La Voce del Paese\u00a0 Tutte le novit\u00e0 presenti in questo numero. Buona lettura a tutti. Editoriale:<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2481","post","type-post","status-publish","format-standard","hentry","category-regione"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/2481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=2481"}],"version-history":[{"count":0,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/2481\/revisions"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=2481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=2481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=2481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}