{"id":2240,"date":"2023-04-12T20:30:02","date_gmt":"2023-04-12T20:30:02","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/04\/12\/niente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione-7\/"},"modified":"2023-04-12T20:30:02","modified_gmt":"2023-04-12T20:30:02","slug":"niente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione-7","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/04\/12\/niente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione-7\/","title":{"rendered":"\u201cNiente da dichiarare?\u201d al Rossini. Ingresso gratuito con prenotazione"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bGioia \u2013 La Voce del Paese\u00a0<\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p><strong>Il Teatro comunale \u201cRossini\u201d ospiter\u00e0<\/strong> <strong>sabato 15 aprile la Compagnia A.Ge.A.<\/strong> di Adeflia con il loro <strong>spettacolo dal titolo \u201cNiente da dichiarare?\u201d<\/strong> nel suo tour che ha gi\u00e0 raccolto 6 sold out in tutta la regione.<\/p>\n<p>Il testo riprende il vaudeville di Hannequin e Veber che vede un doganiere porre la domanda che d\u00e0 nome alla commedia al nobile De Trivelin, neo marito di Paulette Dupont, durante il viaggio di nozze, mentre si accinge ad un rapporto amoroso con la neo sposa.<\/p>\n<p>L\u2019uomo crede di sentire la stessa domanda (che lo inibisce totalmente) tutte le volte che si trova nella stessa situazione, per cui non riesce a consumare il matrimonio. Inizia cos\u00ec un\u2019esilarante corsa alla ricerca di un rimedio che ridia virilit\u00e0 al giovane. Oltre le naturali difficolt\u00e0, si inserisce nella scena l\u2019ex fidanzato della moglie (La Boule), il quale far\u00e0 di tutto per impedire che il feeling torni tra i due sposini ed un mercante di cammelli (Frontignac), marito di Zez\u00e9, amante del padre della sposa, il rispettabile magistrato del Tribunale parigino Beniamino Dupont.<\/p>\n<p><strong>Una commedia ricca di equivoci<\/strong>, dal ritmo frenetico e piccante senza mancare di un linguaggio misurato e di buon gusto, tipico del primo Novecento.<\/p>\n<p><strong>L\u2019inizio dello spettacolo \u00e8 previsto per le ore 20.30 e l\u2019ingresso \u00e8 gratuito<\/strong>, previa prenotazione contattando <strong>Teatralmente Gioia<\/strong>, promotrice dello spettacolo, al numero 328 571 2248, in alternativa tramite e-mail <strong>scrivendo a<\/strong> <a href=\"mailto:teatralmentegioia@gmail.com\">teatralmentegioia@gmail.com<\/a>.<\/p>\n<p><strong>Sar\u00e0 possibile ritirare il proprio biglietto<\/strong> da marted\u00ec 11 a venerd\u00ec 14 dalle ore 17.00 alle 19.00 presso la sede sita in Piazza XX Settembre, 19, Gioia del Colle, in alternativa sabato 15 presso il botteghino del Teatro Rossini dalle 17.30 alle ore 20.00.<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F04%2F12%2Fniente-da-dichiarare-al-rossini-ingresso-gratuito-con-prenotazione%2F&amp;linkname=%E2%80%9CNiente%20da%20dichiarare%3F%E2%80%9D%20al%20Rossini.%20Ingresso%20gratuito%20con%20prenotazione\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bGioia \u2013 La Voce del Paese\u00a0 Il Teatro comunale \u201cRossini\u201d ospiter\u00e0 sabato 15 aprile la Compagnia A.Ge.A. di<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2240","post","type-post","status-publish","format-standard","hentry","category-regione"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/2240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=2240"}],"version-history":[{"count":0,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/2240\/revisions"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=2240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=2240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=2240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}