{"id":1348,"date":"2023-03-09T16:37:32","date_gmt":"2023-03-09T16:37:32","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/03\/09\/furti-in-appartamento-carabinieri-arrestano-tre-georgiani-2\/"},"modified":"2023-03-09T16:37:32","modified_gmt":"2023-03-09T16:37:32","slug":"furti-in-appartamento-carabinieri-arrestano-tre-georgiani-2","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/03\/09\/furti-in-appartamento-carabinieri-arrestano-tre-georgiani-2\/","title":{"rendered":"Furti in appartamento. Carabinieri arrestano tre georgiani"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bGioia \u2013 La Voce del Paese\u00a0<\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p>\u201cI militari della <strong>Sezione Operativa della Compagnia Carabinieri di Gioia del Colle<\/strong>, in collaborazione <strong>con quelli della locale Stazione<\/strong> hanno dato esecuzione ad un\u2019<strong>ordinanza applicativa di misura cautelare personale della custodia in carcere <\/strong>emessa dal GIP del Tribunale di Bari su richiesta della Procura della Repubblica, nella quale vengono riconosciuti gravi indizi di colpevolezza a carico di <strong>un 48enne, di un 46enne e di un 23enne, tutti di origine georgiana<\/strong>, indagati a vario titolo <strong>per due<\/strong>\u00a0 <strong>furti in appartamento<\/strong>, di cui uno tentato, commessi ai danni di abitazioni private ubicate <strong>nelle zone periferiche di Gioia del Colle<\/strong>.<\/p>\n<p>In particolare, secondo l\u2019impostazione accusatoria accolta dal GIP (fatta salva la valutazione nelle fasi successive con il contributo della difesa), i tre indagati si sarebbero resi responsabili dei due episodi delittuosi, entrambi <strong>avvenuti nel dicembre 2022<\/strong>.<\/p>\n<p>Il primo episodio risale alla <strong>mattina del 12 dicembre 2022<\/strong> allorquando i tre indagati, mediante l\u2019utilizzo di chiavi alterate sono riusciti ad accedere in un appartamento all\u2019altezza di quella <strong>via Sandro Pertini<\/strong>, sottraendo danaro contante, due orologi, vari monili in oro ed assegni, <strong>per un valore di circa 12mila euro<\/strong>, poi allontanandosi a piedi, nelle stradine attigue ove sicuramente avevano lasciato in sosta l\u2019autovettura utilizzata per la fuga.<\/p>\n<p>Il secondo episodio risale, invece, alla tarda mattina del <strong>21 dicembre<\/strong> scorso; in tale occasione il 48enne e il 23enne, mediante l\u2019utilizzo di chiavi alterate sono riusciti ad accedere in un appartamento ubicato nelle vicinanze di quella <strong>via Leone<\/strong>, non avendo il tempo di asportare alcunch\u00e9 poich\u00e9 costretti ad allontanarsi in quanto disturbati dalla presenza di alcuni condomini. I due poi venivano visti allontanarsi a bordo di autovettura Saab con targhe di nazionalit\u00e0 francese, condotta da un terzo complice.<\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p>A distanza di qualche ora la stessa autovettura veniva sottoposta a controllo da altro personale delle FF.PP. all\u2019altezza di della Piazza Umberto di Bari, all\u2019interno della quale prendevano posto, oltre ai due fuggitivi, anche il terzo complice 46enne che si trovava alla guida del mezzo. I tre occupanti venivano deferiti in stato di libert\u00e0 alla competente Autorit\u00e0 Giudiziaria per possesso ingiustificato di chiavi alterate e grimaldelli.<\/p>\n<p><strong>Le indagini<\/strong>, condotte dai militari della Sezione Operativa della Compagnia Carabinieri di Gioia del Colle coadiuvati da quelli della locale Stazione Carabinieri, coordinate dalla Procura della Repubblica di Bari, sviluppate per lo pi\u00f9 tramite le dichiarazioni dei testi che hanno identificato gli autori dei due episodi delittuosi nonch\u00e9 l\u2019ausilio di videocamere di sorveglianza privata e l\u2019analisi dei dati estrapolati dai fotogrammi, <strong>hanno consentito di raccogliere gravi indizi di colpevolezza a carico dei tre arrestati.<\/strong><\/p>\n<p>Il quadro indiziario \u00e8 stato condiviso dalla Procura della Repubblica presso il Tribunale Bari, che ha avanzato richiesta di misura cautelare al Gip, il quale ha disposto per i tre la misura cautelare personale della custodia in carcere.<\/p>\n<p>\u00c8 importante sottolineare che <strong>il procedimento si trova nella fase delle indagini preliminari<\/strong> e che, all\u2019esecuzione della misura cautelare odierna, <strong>seguir\u00e0 l\u2019interrogatorio di garanzia e il confronto con la difesa<\/strong> dell\u2019indagato, la cui eventuale colpevolezza, in ordine ai reati contestati, dovr\u00e0 essere accertata in sede di processo nel contraddittorio tra le parti\u201d. [<strong>Uff. Stampa CC Provinciale<\/strong>]<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F09%2Ffurti-in-appartamento-carabinieri-arrestano-tre-georgiani%2F&amp;linkname=Furti%20in%20appartamento.%20Carabinieri%20arrestano%20tre%20georgiani\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bGioia \u2013 La Voce del Paese\u00a0 \u201cI militari della Sezione Operativa della Compagnia Carabinieri di Gioia del Colle,<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1348","post","type-post","status-publish","format-standard","hentry","category-regione"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=1348"}],"version-history":[{"count":0,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1348\/revisions"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=1348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=1348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=1348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}