{"id":1200,"date":"2023-03-03T12:30:37","date_gmt":"2023-03-03T12:30:37","guid":{"rendered":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/03\/03\/strage-di-alberi-in-via-paolo-cassano-19\/"},"modified":"2023-03-03T12:30:37","modified_gmt":"2023-03-03T12:30:37","slug":"strage-di-alberi-in-via-paolo-cassano-19","status":"publish","type":"post","link":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/2023\/03\/03\/strage-di-alberi-in-via-paolo-cassano-19\/","title":{"rendered":"Strage di alberi in Via Paolo Cassano"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bGioia \u2013 La Voce del Paese\u00a0<\/p>\n<div class=\"wp-block-image\">\n<\/div>\n<p>A soccombere sotto i colpi delle motoseghe sono stati questa volta otto pini adulti di discrete dimensioni, la cui chioma, oltre a costituire un ampio riparo per l\u2019avifauna sinantropica, nel periodo estivo garantiva un\u2019estesa zona d\u2019ombra alla via in cui erano ubicati e ai fruitori dell\u2019area attrezzata ivi presente. <strong><\/strong><\/p>\n<p>L\u2019abbattimento delle piante \u00e8 avvenuto contestualmente ai lavori di rifacimento della summenzionata piazzetta e dell\u2019annessa area giochi.<\/p>\n<p>Trattandosi di beni di pubblico interesse, la cui distruzione comporta un danno per l\u2019intera collettivit\u00e0, sarebbe auspicabile che la cittadinanza e i residenti della zona possano essere messi al corrente circa le motivazioni che hanno portato al taglio delle piante.<\/p>\n<p>In particolare sarebbe apprezzabile se l\u2019Amministrazione volesse chiarire chi e perch\u00e9 ha deciso l\u2019abbattimento delle piante; se lo stesso fosse previsto nel progetto di ammodernamento dell\u2019area o se la necessit\u00e0 di eradicazione sia subentrata in seguito e per motivi che dovrebbero essere ben argomentati nella perizia di un tecnico.<\/p>\n<p>Secondo quanto riportato sul profilo Facebook del Comitato cittadino di Zona Via Paolo Cassano, nell\u2019interfacciarsi con i residenti riguardo ai lavori in oggetto, nei mesi scorsi il Sindaco aveva parlato della messa in sicurezza dei marciapiedi, senza tuttavia specificare che la stessa sarebbe avvenuta mediante il taglio degli alberi.<\/p>\n<p>La societ\u00e0 civile diventa progressivamente sempre pi\u00f9 sensibile e attenta alle questioni ambientali e anche alla tutela e alla cura del verde urbano che viene percepito come un bene comune da proteggere e come una risorsa funzionale alla tutela del territorio e all\u2019implementazione della qualit\u00e0 dello stesso.<\/p>\n<p>Per questo motivo sempre pi\u00f9 spesso negli ultimi anni il taglio di un numero crescente di alberi ha scatenato sollevazioni popolari e indignazione da parte della cittadinanza. L\u2019Amministrazione comunale questo lo sa bene. Si ricordi a proposito la vicenda dei Pioppi di Via Donnola, risalente ad un paio di anni fa, quando l\u2019opposizione di un gran numero di cittadini costrinse l\u2019amministrazione a fare un passo indietro in merito all\u2019abbattimento di alberi considerati pericolosi e pericolanti.<\/p>\n<p>Le piattaforme social, strumento ormai imprescindibile delle istituzioni a tutti i livelli, possono essere utilizzate non solamente come cassa di risonanza e vetrina delle iniziative della politica, ma anche per consentire un\u2019interazione pi\u00f9 agevole e snella con i cittadini, anche quando sia necessario rendere note le motivazioni che portano a scelte a volte discutibili e non sempre popolari come l\u2019abbattimento di alberi.<\/p>\n<p>Va da se dunque che se l\u2019Amministrazione, o uno qualunque dei suoi rappresentanti, pu\u00f2 annunciare con orgoglio sul proprio profilo social l\u2019avvio dei lavori di ristrutturazioni di una determinata area, pu\u00f2, allo stesso modo, fornire delucidazioni alla cittadinanza in merito a provvedimenti che si sono rivelati essere meno popolari del previsto.<\/p>\n<p>A prescindere dalle motivazioni relative all\u2019abbattimento e anche qualora queste ultime fossero riconducibili a necessit\u00e0 di pubblica sicurezza \u2013 come spesso viene raccontato ogni qual volta che qualche albero soccombe \u2013 restano al suo, assieme a foglie e a rami spezzati, alcune riflessioni amare.<\/p>\n<p>Guardandosi intorno ci si rende conto che di strade dissestate e di pericoli per l\u2019incolumit\u00e0 pubblica e per la salute, ovunque nel mondo, siamo circondati.<\/p>\n<p>La qualit\u00e0 dell\u2019aria che respiriamo, dell\u2019acqua che beviamo, del cibo che mangiamo, lo stile di vita che conduciamo sembrano essere elementi pi\u00f9 trascurabili di una radice fuori posto o di qualche animale selvatico troppo vicino ai perimetri urbani.<\/p>\n<p>Si legge di progetti rivolti alle scolaresche in cui emerge che l\u2019educazione alimentare nelle scuole italiane \u00e8 appannaggio di alcune multinazionali americane che producono prodotti processati e pieni di zuccheri e che spiegano ai bambini cosa ingoiare a colazione insieme ad un bel bicchiere di latte vaccino (il che sarebbe un po\u2019 come affidare progetti di educazione alla salute al CEO della Philip Morris); il tutto col plauso delle istituzioni e forse pure dei genitori.<\/p>\n<p>A tutto ci\u00f2 che sta avvelenando luoghi e corpi, spesso istituzioni e le societ\u00e0 si genuflettono veneranti.<\/p>\n<p>Ma agli alberi e agli animali no, non si perdona mai niente!<\/p>\n<p>D\u2019altra parte siamo la specie superiore, la pi\u00f9 forte; abbiamo secoli di esperienza nel dominio e nella sottomissione dei pi\u00f9 deboli e dell\u2019ambiente.<\/p>\n<p>\u00c8 molto probabile che i cittadini gioiesi nell\u2019alzare gli occhi al cielo per osservare lo spazio vuoto lasciato dalle chiome degli alberi abbattuti si imbattano nella vista e nel frastuono di qualche velivolo militare che sorvola regolarmente il cielo cittadino.<\/p>\n<p>Certo, poco avrebbero potuto fare quegli alberi per limitare un inquinamento acustico cos\u00ec potente e costante; ma per limitare l\u2019inquinamento dell\u2019aria, nove alberi adulti in pi\u00f9 su un territorio sono sempre meglio che nove alberi adulti in meno.<\/p>\n<p>Sicuramente se ne pianteranno di nuovi, giovani, che avranno bisogno del loro tempo per assorbire smog e Co2.<\/p>\n<p>Nel frattempo qualche amministratore si far\u00e0 un bel selfie con i giovani arbusti e con le giostrine nuove di zecca e non mancher\u00e0, in questo caso, di postarlo sui social, come a voler dire, ad adulti e bambini: \u201cGuardate, stiamo lavorando per voi\u201d. Si, alla fine del mondo! [<strong>di Ivana Guagnano]<\/strong><\/p>\n<p><strong>HAN SRADICATO UN ALBERO<\/strong><\/p>\n<p>Han sradicato un albero.<\/p>\n<p>Ancora stamani<\/p>\n<p>il vento, il sole, gli uccelli<\/p>\n<p>l\u2019accarezzavano benignamente. Era<\/p>\n<p>felice e giovane, candido e eretto,<\/p>\n<p>con una chiara vocazione di cielo<\/p>\n<p>e un alto futuro di stelle.<\/p>\n<p>Stasera giace come un bimbo<\/p>\n<p>esiliato dalla sua culla, spezzate<\/p>\n<p>le tenere gambe, affondato<\/p>\n<p>il capo, sparso per terra e triste,<\/p>\n<p>disfatto in foglie<\/p>\n<p>e in pianto ancora verde, in pianto.<\/p>\n<p>Questa notte uscir\u00f2 \u2013 quando nessuno<\/p>\n<p>potr\u00e0 vedere, quando sar\u00f2 solo-<\/p>\n<p>a chiudergli gli occhi ed a cantargli<\/p>\n<p>quella canzone che stamani il vento<\/p>\n<p>passando sussurrava.<\/p>\n<p><strong>Rafael Alberti<\/strong><\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Flavocedelpaese.info%2Findex.php%2F2023%2F03%2F02%2Fstrage-di-alberi-in-via-paolo-cassano%2F&amp;linkname=Strage%20di%20alberi%20in%20Via%20Paolo%20Cassano\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bGioia \u2013 La Voce del Paese\u00a0 A soccombere sotto i colpi delle motoseghe sono stati questa volta otto<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1200","post","type-post","status-publish","format-standard","hentry","category-regione"],"_links":{"self":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=1200"}],"version-history":[{"count":0,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1200\/revisions"}],"wp:attachment":[{"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=1200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=1200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casamassima.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=1200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}